{"id":11417,"date":"2024-06-19T10:14:39","date_gmt":"2024-06-19T08:14:39","guid":{"rendered":"https:\/\/www.vezzosisrl.com\/prodotto\/sistema-poggiagambe-regolabile-elettricamente-copy\/"},"modified":"2024-07-19T08:58:39","modified_gmt":"2024-07-19T06:58:39","slug":"seduta-lavaggio-massaggio-relax-ad-aria","status":"publish","type":"product","link":"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/","title":{"rendered":"3227 Poltrona massaggiante CU29 WASH MASSAGE"},"content":{"rendered":"<p>Poltrona lavaggio con massaggio totale ad aria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poltrona lavaggio con massaggio totale ad aria.<\/p>\n","protected":false},"featured_media":11422,"template":"","meta":[],"product_brand":[],"product_cat":[184],"product_tag":[],"class_list":["post-11417","product","type-product","status-publish","has-post-thumbnail","product_cat-lavaggi","pa_collezione-collezione-cu29-poltrone-lavaggio-parrucchiere","first","instock","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3227 Poltrona massaggiante CU29 WASH MASSAGE<\/title>\n<meta name=\"description\" content=\"CU29 WASH MASSAGE \u00e8 una seduta di lavaggio per negozio da parrucchiere con incorporato un massaggio ad aria totale su tutto il corpo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vezzosisrl.com\/es\/seduta-lavaggio-massaggio-relax-ad-aria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3227 Poltrona massaggiante CU29 WASH MASSAGE\" \/>\n<meta property=\"og:description\" content=\"CU29 WASH MASSAGE \u00e8 una seduta di lavaggio per negozio da parrucchiere con incorporato un massaggio ad aria totale su tutto il corpo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/\" \/>\n<meta property=\"og:site_name\" content=\"Vezzosi Arredamenti\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-19T06:58:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2024\/06\/3227-cu29-wash-massage.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/\",\"url\":\"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/\",\"name\":\"3227 Poltrona massaggiante CU29 WASH MASSAGE\",\"isPartOf\":{\"@id\":\"https:\/\/www.vezzosisrl.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2024\/06\/3227-cu29-wash-massage.jpg\",\"datePublished\":\"2024-06-19T08:14:39+00:00\",\"dateModified\":\"2024-07-19T06:58:39+00:00\",\"description\":\"CU29 WASH MASSAGE \u00e8 una seduta di lavaggio per negozio da parrucchiere con incorporato un massaggio ad aria totale su tutto il corpo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/#primaryimage\",\"url\":\"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2024\/06\/3227-cu29-wash-massage.jpg\",\"contentUrl\":\"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2024\/06\/3227-cu29-wash-massage.jpg\",\"width\":800,\"height\":800,\"caption\":\"3227-cu29-wash-massage\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vezzosisrl.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/www.vezzosisrl.com\/prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"3227 Poltrona massaggiante CU29 WASH MASSAGE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vezzosisrl.com\/es\/#website\",\"url\":\"https:\/\/www.vezzosisrl.com\/es\/\",\"name\":\"Vezzosi Arredamenti\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vezzosisrl.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3227 Poltrona massaggiante CU29 WASH MASSAGE","description":"CU29 WASH MASSAGE \u00e8 una seduta di lavaggio per negozio da parrucchiere con incorporato un massaggio ad aria totale su tutto il corpo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vezzosisrl.com\/es\/seduta-lavaggio-massaggio-relax-ad-aria\/","og_locale":"es_ES","og_type":"article","og_title":"3227 Poltrona massaggiante CU29 WASH MASSAGE","og_description":"CU29 WASH MASSAGE \u00e8 una seduta di lavaggio per negozio da parrucchiere con incorporato un massaggio ad aria totale su tutto il corpo.","og_url":"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/","og_site_name":"Vezzosi Arredamenti","article_modified_time":"2024-07-19T06:58:39+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2024\/06\/3227-cu29-wash-massage.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/","url":"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/","name":"3227 Poltrona massaggiante CU29 WASH MASSAGE","isPartOf":{"@id":"https:\/\/www.vezzosisrl.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/#primaryimage"},"image":{"@id":"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2024\/06\/3227-cu29-wash-massage.jpg","datePublished":"2024-06-19T08:14:39+00:00","dateModified":"2024-07-19T06:58:39+00:00","description":"CU29 WASH MASSAGE \u00e8 una seduta di lavaggio per negozio da parrucchiere con incorporato un massaggio ad aria totale su tutto il corpo.","breadcrumb":{"@id":"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/#primaryimage","url":"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2024\/06\/3227-cu29-wash-massage.jpg","contentUrl":"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2024\/06\/3227-cu29-wash-massage.jpg","width":800,"height":800,"caption":"3227-cu29-wash-massage"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vezzosisrl.com\/seduta-lavaggio-massaggio-relax-ad-aria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vezzosisrl.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/www.vezzosisrl.com\/prodotti\/"},{"@type":"ListItem","position":3,"name":"3227 Poltrona massaggiante CU29 WASH MASSAGE"}]},{"@type":"WebSite","@id":"https:\/\/www.vezzosisrl.com\/es\/#website","url":"https:\/\/www.vezzosisrl.com\/es\/","name":"Vezzosi Arredamenti","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vezzosisrl.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.vezzosisrl.com\/es\/wp-json\/wp\/v2\/product\/11417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vezzosisrl.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vezzosisrl.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vezzosisrl.com\/es\/wp-json\/wp\/v2\/media\/11422"}],"wp:attachment":[{"href":"https:\/\/www.vezzosisrl.com\/es\/wp-json\/wp\/v2\/media?parent=11417"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.vezzosisrl.com\/es\/wp-json\/wp\/v2\/product_brand?post=11417"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vezzosisrl.com\/es\/wp-json\/wp\/v2\/product_cat?post=11417"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vezzosisrl.com\/es\/wp-json\/wp\/v2\/product_tag?post=11417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}