{"id":9068,"date":"2023-05-26T12:48:12","date_gmt":"2023-05-26T10:48:12","guid":{"rendered":"http:\/\/vsrl.sviluppokeyweb.com\/prodotto\/3075-beauty-basket-flora\/"},"modified":"2024-01-10T11:34:44","modified_gmt":"2024-01-10T10:34:44","slug":"beauty-basket-flora-seduta-lavaggio-professionale-per-salone","status":"publish","type":"product","link":"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/","title":{"rendered":"3075 \u2013 BEAUTY BASKET FLORA"},"content":{"rendered":"<p>Le fort caract\u00e8re contemporain et exclusif de la collection Flora est exprim\u00e9 par les stations de lavage Flora Beauty Basket. Les couleurs claires et les lignes douces et ondulantes \u00e9voquent imm\u00e9diatement l&#8217;accueil et le confort. Chaque fauteuil est \u00e9quip\u00e9 d&#8217;un lavabo et d&#8217;un dossier inclinables, y compris dans la version Basic ; le mod\u00e8le Relax est en outre dot\u00e9 d&#8217;un repose-jambes r\u00e9glable \u00e9lectroniquement. Pour enrichir encore l&#8217;exp\u00e9rience de vos clients, nous vous recommandons le mod\u00e8le Massage, dot\u00e9 d&#8217;un massage corporel total par drainage lymphatique \u00e0 flux d&#8217;air variable en continu.<\/p>\n<p>Vous voulez encore plus pour votre salon? Flora Beauty Basket c&#8217;est le mieux en mati\u00e8re de bacs de lavage.\u00a0 Le cadre est recouvert de ska\u00ef, tout comme les c\u00f4t\u00e9s avec des ouvertures en verre lamin\u00e9 transparent. Le compl\u00e9ment est \u00e9galement dot\u00e9 d&#8217;une coque sup\u00e9rieure inclinable avec une fa\u00e7ade en plexiglas blanc et un syst\u00e8me de r\u00e9tro-\u00e9clairage par LED pour am\u00e9liorer la visibilit\u00e9 \u00e0 l&#8217;int\u00e9rieur de la baignoire, et d&#8217;une arri\u00e8re en plexiglas transparent avec une fonction d&#8217;a\u00e9ration. Dans ses extensions Relax et Massage, Beauty Basket est un fauteuil dot\u00e9 d&#8217;un repose-jambes r\u00e9glable \u00e9lectroniquement et d&#8217;un massage par drainage lymphatique total. Le grand avantage de cette station de lavage professionnelle est qu&#8217;elle peut \u00eatre reproduit en s\u00e9rie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fort caract\u00e8re contemporain et exclusif de la collection Flora est exprim\u00e9 par les stations de lavage Flora Beauty Basket. Les couleurs claires et les lignes douces et ondulantes \u00e9voquent imm\u00e9diatement l&#8217;accueil et le confort. Chaque fauteuil est \u00e9quip\u00e9 d&#8217;un lavabo et d&#8217;un dossier inclinables, y compris dans la version Basic ; le mod\u00e8le Relax&#8230;<\/p>\n","protected":false},"featured_media":6967,"template":"","meta":[],"product_brand":[],"product_cat":[463],"product_tag":[],"class_list":["post-9068","product","type-product","status-publish","has-post-thumbnail","product_cat-bacs-de-lavage","pa_collezione-vezzosi-style-fr","pa_collezione-meubles-elegants-coiffeur-barbier-pour-detaillants-et-magasins","pa_tipologie-prix-bacs-de-lavage-cheveux-doubles-pour-coiffeurs-vasque-basculante","first","instock","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3075 \u2013 BEAUTY BASKET FLORA - Vezzosi Arredamenti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3075 \u2013 BEAUTY BASKET FLORA - Vezzosi Arredamenti\" \/>\n<meta property=\"og:description\" content=\"Le fort caract\u00e8re contemporain et exclusif de la collection Flora est exprim\u00e9 par les stations de lavage Flora Beauty Basket. Les couleurs claires et les lignes douces et ondulantes \u00e9voquent imm\u00e9diatement l&#8217;accueil et le confort. Chaque fauteuil est \u00e9quip\u00e9 d&#8217;un lavabo et d&#8217;un dossier inclinables, y compris dans la version Basic ; le mod\u00e8le Relax...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/\" \/>\n<meta property=\"og:site_name\" content=\"Vezzosi Arredamenti\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-10T10:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2023\/05\/Lavaggio-beauty-basket-flora.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/\",\"url\":\"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/\",\"name\":\"3075 \u2013 BEAUTY BASKET FLORA - Vezzosi Arredamenti\",\"isPartOf\":{\"@id\":\"https:\/\/www.vezzosisrl.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2023\/05\/Lavaggio-beauty-basket-flora.jpg\",\"datePublished\":\"2023-05-26T10:48:12+00:00\",\"dateModified\":\"2024-01-10T10:34:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/#primaryimage\",\"url\":\"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2023\/05\/Lavaggio-beauty-basket-flora.jpg\",\"contentUrl\":\"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2023\/05\/Lavaggio-beauty-basket-flora.jpg\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vezzosisrl.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\/\/www.vezzosisrl.com\/prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"3075 \u2013 BEAUTY BASKET FLORA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vezzosisrl.com\/fr\/#website\",\"url\":\"https:\/\/www.vezzosisrl.com\/fr\/\",\"name\":\"Vezzosi Arredamenti\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vezzosisrl.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3075 \u2013 BEAUTY BASKET FLORA - Vezzosi Arredamenti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/","og_locale":"fr_FR","og_type":"article","og_title":"3075 \u2013 BEAUTY BASKET FLORA - Vezzosi Arredamenti","og_description":"Le fort caract\u00e8re contemporain et exclusif de la collection Flora est exprim\u00e9 par les stations de lavage Flora Beauty Basket. Les couleurs claires et les lignes douces et ondulantes \u00e9voquent imm\u00e9diatement l&#8217;accueil et le confort. Chaque fauteuil est \u00e9quip\u00e9 d&#8217;un lavabo et d&#8217;un dossier inclinables, y compris dans la version Basic ; le mod\u00e8le Relax...","og_url":"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/","og_site_name":"Vezzosi Arredamenti","article_modified_time":"2024-01-10T10:34:44+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2023\/05\/Lavaggio-beauty-basket-flora.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/","url":"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/","name":"3075 \u2013 BEAUTY BASKET FLORA - Vezzosi Arredamenti","isPartOf":{"@id":"https:\/\/www.vezzosisrl.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/#primaryimage"},"image":{"@id":"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2023\/05\/Lavaggio-beauty-basket-flora.jpg","datePublished":"2023-05-26T10:48:12+00:00","dateModified":"2024-01-10T10:34:44+00:00","breadcrumb":{"@id":"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/#primaryimage","url":"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2023\/05\/Lavaggio-beauty-basket-flora.jpg","contentUrl":"https:\/\/www.vezzosisrl.com\/wp-content\/uploads\/2023\/05\/Lavaggio-beauty-basket-flora.jpg","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.vezzosisrl.com\/fr\/beauty-basket-flora-fauteuil-lavage-professionnel-pour-salon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vezzosisrl.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vezzosisrl.com\/prodotti\/"},{"@type":"ListItem","position":3,"name":"3075 \u2013 BEAUTY BASKET FLORA"}]},{"@type":"WebSite","@id":"https:\/\/www.vezzosisrl.com\/fr\/#website","url":"https:\/\/www.vezzosisrl.com\/fr\/","name":"Vezzosi Arredamenti","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vezzosisrl.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.vezzosisrl.com\/fr\/wp-json\/wp\/v2\/product\/9068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vezzosisrl.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vezzosisrl.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vezzosisrl.com\/fr\/wp-json\/wp\/v2\/media\/6967"}],"wp:attachment":[{"href":"https:\/\/www.vezzosisrl.com\/fr\/wp-json\/wp\/v2\/media?parent=9068"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.vezzosisrl.com\/fr\/wp-json\/wp\/v2\/product_brand?post=9068"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vezzosisrl.com\/fr\/wp-json\/wp\/v2\/product_cat?post=9068"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vezzosisrl.com\/fr\/wp-json\/wp\/v2\/product_tag?post=9068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}